{"id":679332614,"date":"2026-09-01T14:21:42","date_gmt":"2026-09-01T19:21:42","guid":{"rendered":"https:\/\/www.eisgroup.com\/cartographie-des-transferts-de-donnees-de-sante\/"},"modified":"2026-09-02T16:05:18","modified_gmt":"2026-09-02T21:05:18","slug":"cartographie-des-transferts-de-donnees-de-sante","status":"publish","type":"page","link":"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/","title":{"rendered":"Cartographie des transferts de donn\u00e9es de sant\u00e9"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; background_color=&#8221;#008568&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#008568 0%|rgba(0,133,104,0.63) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.eisgroup.com\/wp-content\/uploads\/2026\/09\/background_green_centered.jpg&#8221; vertical_offset_tablet=&#8221;&#8221; vertical_offset_phone=&#8221;&#8221; vertical_offset_last_edited=&#8221;on|phone&#8221; min_height=&#8221;174px&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;||60px||false|false&#8221; bottom_divider_color=&#8221;#ffffff&#8221; bottom_divider_height=&#8221;25px&#8221; bottom_divider_flip=&#8221;vertical&#8221; bottom_divider_arrangement=&#8221;above_content&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row make_equal=&#8221;on&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.6&#8243; min_height=&#8221;175px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;50px||50px||false|false&#8221; custom_padding_tablet=&#8221;180px||||false|false&#8221; custom_padding_phone=&#8221;100px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; header_text_align=&#8221;center&#8221; header_font_size=&#8221;3em&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;#ffffff&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;||-10px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1 style=\"text-align: center;\"><b>H\u00e9bergement de donn\u00e9es de sant\u00e9<\/b>:<\/h1>\n<h2 style=\"text-align: center;\"><b>Certification HDS en cours d&#8217;obtention<\/b><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EFEFF9&#8243; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; header_2_font_size=&#8221;1.5em&#8221; header_2_line_height=&#8221;1.5em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><span>EIS Software LTD (Irlande) a pass\u00e9 avec succ\u00e8s l&#8217;audit officiel d&#8217;H\u00e9bergeur de Donn\u00e9es de Sant\u00e9 (HDS) et est actuellement dans l&#8217;attente de la d\u00e9livrance formelle de son certificat. Cette d\u00e9marche de conformit\u00e9 s&#8217;applique sp\u00e9cifiquement \u00e0<\/span> EIS OneSuite\u2122.<\/p>\n<p><span>Afin d&#8217;offrir le plus haut niveau de s\u00e9curit\u00e9, notre service est h\u00e9berg\u00e9 sur l&#8217;infrastructure d&#8217;Amazon Web Services (AWS), sp\u00e9cifiquement sur la R\u00e9gion France 3 (Paris). AWS est un fournisseur Cloud pleinement certifi\u00e9 HDS pour l&#8217;h\u00e9bergement physique. En s&#8217;appuyant sur cette base s\u00e9curis\u00e9e, EIS Software LTD a pass\u00e9 avec succ\u00e8s son propre audit HDS couvrant ses r\u00f4les op\u00e9rationnels et administratifs, garantissant ainsi une protection de bout en bout de vos donn\u00e9es de sant\u00e9.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;\u00c9tat d&#8217;avancement et p\u00e9rim\u00e8tre audit\u00e9&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Transparency is at the core of our operations. Below is the current status of our HDS compliance process:<\/p>\n<p>[\/et_pb_text][difl_datatable row_odd_background_bgcolor=&#8221;#EFEFF9&#8243; row_first_column_background_bgcolor=&#8221;#2A2A72&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; row_first_column_text_font=&#8221;|700|||||||&#8221; row_first_column_text_text_align=&#8221;right&#8221; row_first_column_text_text_color=&#8221;#ffffff&#8221; hover_enabled=&#8221;0&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; body_cell_padding=&#8221;15px|15px|15px|15px|false|false&#8221;][difl_datatableitem row=&#8221;Statut<br \/>\nAudit valid\u00e9, certification formelle en attente d&#8217;\u00e9mission.&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Entit\u00e9 audit\u00e9e<br \/>\nEIS Software LTD (Irlande).&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;P\u00e9rim\u00e8tre op\u00e9rationnel<br \/>\nL&#8217;audit couvre notre entit\u00e9 juridique ainsi que les op\u00e9rations men\u00e9es depuis nos bureaux europ\u00e9ens situ\u00e9s en Lituanie, Lettonie et Pologne.&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Version HDS<br \/>\nHDS v2.0&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Organisme auditeur<br \/>\nAFNOR&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Date de validation de l&#8217;audit<br \/>\nAout, 2026&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Date d&#8217;obtention pr\u00e9vue<br \/>\nQ4 2026&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][\/difl_datatable][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; custom_margin=&#8221;||||false|false&#8221; border_color_left=&#8221;#3ACEA9&#8243; border_width_left=&#8221;5px&#8221; custom_padding=&#8221;15px||15px|30px|false|false&#8221; background_color=&#8221;#EFEFF9&#8243;]<\/p>\n<p>Notre certificat HDS officiel sera disponible au t\u00e9l\u00e9chargement ici, et notre entit\u00e9 appara\u00eetra dans l&#8217;annuaire officiel HDS de l&#8217;ANS, d\u00e8s sa d\u00e9livrance formelle.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=&#8221;P\u00e9rim\u00e8tre de l&#8217;audit HDS&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><span>La certification HDS repose sur un mod\u00e8le de responsabilit\u00e9 partag\u00e9e. Tandis qu&#8217;AWS fournit l&#8217;infrastructure physique certifi\u00e9e HDS, l&#8217;audit valid\u00e9 par EIS Software LTD couvre de mani\u00e8re stricte les activit\u00e9s suivantes<\/span><\/p>\n<p>[\/et_pb_text][difl_datatable row_odd_background_bgcolor=&#8221;#EFEFF9&#8243; row_first_column_background_bgcolor=&#8221;#2A2A72&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; row_first_column_text_font=&#8221;|700|||||||&#8221; row_first_column_text_text_align=&#8221;right&#8221; row_first_column_text_text_color=&#8221;#ffffff&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; body_cell_padding=&#8221;15px|15px|15px|15px|false|false&#8221;][difl_datatableitem row=&#8221;Activit\u00e9 3<br \/>\nLa mise \u00e0 disposition et le maintien en condition op\u00e9rationnelle de la plateforme d&#8217;h\u00e9bergement d&#8217;applications.&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Activit\u00e9 4<br \/>\nLa mise \u00e0 disposition et le maintien en condition op\u00e9rationnelle de l&#8217;infrastructure virtuelle.&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Activit\u00e9 5<br \/>\nL&#8217;administration et l&#8217;exploitation du syst\u00e8me d&#8217;information.&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][\/difl_datatable][et_pb_heading title=&#8221;Localisation et r\u00e9sidence des donn\u00e9es&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>EIS Software LTD ne g\u00e8re pas de centres de donn\u00e9es physiques. L&#8217;int\u00e9gralit\u00e9 des donn\u00e9es de sant\u00e9 est h\u00e9berg\u00e9e et trait\u00e9e de mani\u00e8re s\u00e9curis\u00e9e sur AWS R\u00e9gion France 3 (Paris).<\/p>\n<p>Nous garantissons que tous les traitements, le stockage et les sauvegardes des donn\u00e9es s&#8217;effectuent strictement au sein de l&#8217;Union europ\u00e9enne (UE), assurant une conformit\u00e9 absolue avec les lois europ\u00e9ennes sur la souverainet\u00e9 des donn\u00e9es et la r\u00e9glementation fran\u00e7aise.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=&#8221;Nos engagements en mati\u00e8re de s\u00e9curit\u00e9&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Dans le cadre de notre d\u00e9marche HDS, nos processus internes appliquent d&#8217;ores et d\u00e9j\u00e0 les mesures de s\u00e9curit\u00e9 les plus strictes. En combinant les fonctionnalit\u00e9s de s\u00e9curit\u00e9 d&#8217;AWS et nos propres protocoles, nous assurons:<\/p>\n<p>[\/et_pb_text][difl_datatable row_odd_background_bgcolor=&#8221;#EFEFF9&#8243; row_first_column_background_bgcolor=&#8221;#2A2A72&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; row_first_column_text_font=&#8221;|700|||||||&#8221; row_first_column_text_text_align=&#8221;right&#8221; row_first_column_text_text_color=&#8221;#ffffff&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; body_cell_padding=&#8221;15px|15px|15px|15px|false|false&#8221;][difl_datatableitem row=&#8221;Contr\u00f4le d&#8217;acc\u00e8s<br \/>\nGestion des acc\u00e8s selon le principe du moindre privil\u00e8ge, autorisations bas\u00e9es sur les r\u00f4les et authentification multifacteur (MFA) appliqu\u00e9es \u00e0 l&#8217;ensemble de nos bureaux op\u00e9rationnels.&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Chiffrement<br \/>\nProtocoles de chiffrement avanc\u00e9s pour toutes les donn\u00e9es, en transit comme au repos.&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Audit et supervision<br \/>\nJournalisation continue, d\u00e9tection des menaces et surveillance des syst\u00e8mes 24\/7.&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][difl_datatableitem row=&#8221;Gestion des incidents<br \/>\n\u00c9quipe de s\u00e9curit\u00e9 d\u00e9di\u00e9e avec un processus de r\u00e9ponse rapide aux incidents.&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/difl_datatableitem][\/difl_datatable][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EFEFF9&#8243; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Transparence et contacts&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-WEB:ceb9690a-bc02-4d87-875a-0fd0e7525b65-1\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:ceb9690a-bc02-4d87-875a-0fd0e7525b65-1\" data-turn-id-container=\"request-WEB:ceb9690a-bc02-4d87-875a-0fd0e7525b65-1\" data-testid=\"conversation-turn-4\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div data-conversation-screenshot-content=\"\" class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden @[53.5rem]\/main:[--thread-content-max-width:48rem] relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div data-message-author-role=\"assistant\" data-message-id=\"8334402d-1807-5985-8dcd-bf47d5f63bec\" data-turn-start-message=\"true\" dir=\"auto\" data-message-model-slug=\"gpt-5.6-terra-wm\" class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" tabindex=\"0\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"90\" data-is-last-node=\"\" data-is-only-node=\"\" class=\"PDq2pG_selectionAnchorContainer\">Nous croyons en une transparence totale quant \u00e0 la mani\u00e8re dont vos donn\u00e9es sont trait\u00e9es.<span aria-hidden=\"true\" class=\"PDq2pG_selectionAnchor\"><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<div class=\"mt-3 w-full empty:hidden has-[&gt;_:empty]:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<div data-conversation-screenshot-content=\"\" class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<div aria-hidden=\"true\" class=\"pointer-events-none -mt-px h-px translate-y-(--scroll-root-safe-area-inset-bottom)\"><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_css_free_form=&#8221;.ba_flipbox_0 .dtq-flipbox-front-card, .ba_flipbox_0 .dtq-flipbox-back-card {height:245px!important;}&#8221; sticky_enabled=&#8221;0&#8243; locked=&#8221;off&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][ba_icon_box icon=&#8221;&#xf56d;||fa||900&#8243; title=&#8221;Politique de confidentialit\u00e9 et Accord de traitement des donn\u00e9es (DPA)&#8221; icon_color=&#8221;#007AAF&#8221; icon_width=&#8221;60px&#8221; icon_height=&#8221;60px&#8221; icon_spacing=&#8221;15px&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; title_text_color=&#8221;#007AAF&#8221; title_font_size=&#8221;1rem&#8221; title_line_height=&#8221;1.2em&#8221; description_font_size=&#8221;1rem&#8221; description_line_height=&#8221;1.4em&#8221; background_color=&#8221;#ffffff&#8221; min_height=&#8221;245px&#8221; hover_enabled=&#8221;0&#8243; border_radii_box=&#8221;on||||&#8221; border_width_all_box=&#8221;0px&#8221; box_shadow_style_item=&#8221;preset3&#8243; box_shadow_color_item=&#8221;rgba(0,0,0,0.1)&#8221; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|desktop&#8221; background_color__hover=&#8221;#ffffff&#8221; background_enable_color__hover=&#8221;on&#8221; title_text_color__hover_enabled=&#8221;on|desktop&#8221; title_text_color__hover=&#8221;#007AAF&#8221; icon_color__hover_enabled=&#8221;on|desktop&#8221; icon_color__hover=&#8221;#00A7E1&#8243; link_option_url=&#8221;https:\/\/www.eisgroup.com\/privacy-statement\/&#8221; sticky_enabled=&#8221;0&#8243; border_width_all_box__hover_enabled=&#8221;on|desktop&#8221; border_color_all_box__hover_enabled=&#8221;on|hover&#8221; border_width_all_box__hover=&#8221;5px&#8221; border_color_all_box__hover=&#8221;#00A7E1&#8243; link_option_url_new_window=&#8221;on&#8221;][\/ba_icon_box][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][ba_flipbox front_title=&#8221;Liste des sous-traitants et fournisseurs Cloud&#8221; front_padding=&#8221;0px|0px|0px|0px&#8221; front_img_width=&#8221;60px&#8221; front_img_height=&#8221;92px&#8221; front_bg_color=&#8221;#ffffff&#8221; border_radii_front_media=&#8221;on|100px|100px|100px|100px&#8221; front_title_font_size=&#8221;1rem&#8221; front_description_font_size=&#8221;1rem&#8221; front_desc_spacing=&#8221;10px&#8221; border_radii_card=&#8221;on||||&#8221; border_color_all_card=&#8221;RGBA(255,255,255,0)&#8221; back_media_type=&#8221;none&#8221; back_title=&#8221;Liste des sous-traitants et fournisseurs Cloud&#8221; back_description=&#8221;Amazon Web Services (AWS),  DataDog, CyberArk\/Idira, Fivetran, SIA EIS Group     , UAB EIS Group Lietuva, EIS Software Poland Sp.z.o.o. , EIS Software Limited&#8221; back_padding=&#8221;0px|0px|0px|0px&#8221; back_img_width=&#8221;120px&#8221; back_img_height=&#8221;120px&#8221; back_bg_color=&#8221;#ffffff&#8221; border_radii_back_media=&#8221;on|100px|100px|100px|100px&#8221; back_title_font_size=&#8221;1rem&#8221; back_title_text_color=&#8221;#2A2A72&#8243; back_description_font_size=&#8221;1rem&#8221; back_description_text_color=&#8221;#2A2A72&#8243; back_desc_spacing=&#8221;10px&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; front_icon=&#8221;&#xf46d;||fa||900&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; front_ct_padding=&#8221;30px|30px|30px|30px|false|false&#8221; front_icon_color=&#8221;#007AAF&#8221; front_title_text_color=&#8221;#007AAF&#8221; front_title_font=&#8221;|700|||||||&#8221; animation_type=&#8221;fade&#8221; box_shadow_style_card=&#8221;preset3&#8243; back_bg_enable_color=&#8221;on&#8221; back_ct_padding=&#8221;30px|30px|30px|30px|false|false&#8221; back_title_font=&#8221;|700|||||||&#8221; max_height=&#8221;245px&#8221; locked=&#8221;off&#8221; height=&#8221;245px&#8221; custom_css_main_element=&#8221;height:245px!important;&#8221;][\/ba_flipbox][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Contacter notre \u00e9quipe de s\u00e9curit\u00e9 :&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: center;\"><strong>D\u00e9l\u00e9gu\u00e9 \u00e0 la Protection des Donn\u00e9es (DPO)<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;mailto:dpo@eeisgroup.com&#8221; button_text=&#8221;dpo@eisgroup.com&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; button_text_size=&#8221;16px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: center;\"><strong>Questions de s\u00e9curit\u00e9<span>\u00a0<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;mailto:incident.notifications@eisgroup.com&#8221; button_text=&#8221;incident.notifications@eisgroup.com&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; button_text_size=&#8221;15px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e9bergement de donn\u00e9es de sant\u00e9: Certification HDS en cours d&#8217;obtentionEIS Software LTD (Irlande) a pass\u00e9 avec succ\u00e8s l&#8217;audit officiel d&#8217;H\u00e9bergeur de Donn\u00e9es de Sant\u00e9 (HDS) et est actuellement dans l&#8217;attente de la d\u00e9livrance formelle de son certificat. Cette d\u00e9marche de conformit\u00e9 s&#8217;applique sp\u00e9cifiquement \u00e0 EIS OneSuite\u2122. Afin d&#8217;offrir le plus haut niveau de s\u00e9curit\u00e9, notre\u2026 <a href=\"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/\">Read More &raquo;<\/a><\/p>\n","protected":false},"author":30,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"difl_page_category":[],"class_list":["post-679332614","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartographie des transferts de donn\u00e9es de sant\u00e9 - EIS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartographie des transferts de donn\u00e9es de sant\u00e9 - EIS\" \/>\n<meta property=\"og:description\" content=\"H\u00e9bergement de donn\u00e9es de sant\u00e9: Certification HDS en cours d&#039;obtentionEIS Software LTD (Irlande) a pass\u00e9 avec succ\u00e8s l&#039;audit officiel d&#039;H\u00e9bergeur de Donn\u00e9es de Sant\u00e9 (HDS) et est actuellement dans l&#039;attente de la d\u00e9livrance formelle de son certificat. Cette d\u00e9marche de conformit\u00e9 s&#039;applique sp\u00e9cifiquement \u00e0 EIS OneSuite\u2122. Afin d&#039;offrir le plus haut niveau de s\u00e9curit\u00e9, notre\u2026 Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"EIS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T21:05:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/cartographie-des-transferts-de-donnees-de-sante\\\/\",\"url\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/cartographie-des-transferts-de-donnees-de-sante\\\/\",\"name\":\"Cartographie des transferts de donn\u00e9es de sant\u00e9 - EIS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-09-01T19:21:42+00:00\",\"dateModified\":\"2026-09-02T21:05:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/cartographie-des-transferts-de-donnees-de-sante\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/cartographie-des-transferts-de-donnees-de-sante\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/cartographie-des-transferts-de-donnees-de-sante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartographie des transferts de donn\u00e9es de sant\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/\",\"name\":\"EIS\",\"description\":\"Digital Insurance Platform\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/#organization\",\"name\":\"EIS\",\"url\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eisgroup.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/eis-logo-panel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eisgroup.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/eis-logo-panel.jpg\",\"width\":1200,\"height\":628,\"caption\":\"EIS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eisgroup.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/@EISGroupLtd\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/eisgroupltd\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartographie des transferts de donn\u00e9es de sant\u00e9 - EIS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/","og_locale":"fr_FR","og_type":"article","og_title":"Cartographie des transferts de donn\u00e9es de sant\u00e9 - EIS","og_description":"H\u00e9bergement de donn\u00e9es de sant\u00e9: Certification HDS en cours d'obtentionEIS Software LTD (Irlande) a pass\u00e9 avec succ\u00e8s l'audit officiel d'H\u00e9bergeur de Donn\u00e9es de Sant\u00e9 (HDS) et est actuellement dans l'attente de la d\u00e9livrance formelle de son certificat. Cette d\u00e9marche de conformit\u00e9 s'applique sp\u00e9cifiquement \u00e0 EIS OneSuite\u2122. Afin d'offrir le plus haut niveau de s\u00e9curit\u00e9, notre\u2026 Read More &raquo;","og_url":"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/","og_site_name":"EIS","article_modified_time":"2026-09-02T21:05:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/","url":"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/","name":"Cartographie des transferts de donn\u00e9es de sant\u00e9 - EIS","isPartOf":{"@id":"https:\/\/www.eisgroup.com\/fr\/#website"},"datePublished":"2026-09-01T19:21:42+00:00","dateModified":"2026-09-02T21:05:18+00:00","breadcrumb":{"@id":"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eisgroup.com\/fr\/cartographie-des-transferts-de-donnees-de-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eisgroup.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Cartographie des transferts de donn\u00e9es de sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.eisgroup.com\/fr\/#website","url":"https:\/\/www.eisgroup.com\/fr\/","name":"EIS","description":"Digital Insurance Platform","publisher":{"@id":"https:\/\/www.eisgroup.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eisgroup.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eisgroup.com\/fr\/#organization","name":"EIS","url":"https:\/\/www.eisgroup.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eisgroup.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.eisgroup.com\/wp-content\/uploads\/2025\/05\/eis-logo-panel.jpg","contentUrl":"https:\/\/www.eisgroup.com\/wp-content\/uploads\/2025\/05\/eis-logo-panel.jpg","width":1200,"height":628,"caption":"EIS"},"image":{"@id":"https:\/\/www.eisgroup.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/@EISGroupLtd","https:\/\/www.linkedin.com\/company\/eisgroupltd"]}]}},"_links":{"self":[{"href":"https:\/\/www.eisgroup.com\/fr\/wp-json\/wp\/v2\/pages\/679332614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eisgroup.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eisgroup.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eisgroup.com\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eisgroup.com\/fr\/wp-json\/wp\/v2\/comments?post=679332614"}],"version-history":[{"count":6,"href":"https:\/\/www.eisgroup.com\/fr\/wp-json\/wp\/v2\/pages\/679332614\/revisions"}],"predecessor-version":[{"id":679332816,"href":"https:\/\/www.eisgroup.com\/fr\/wp-json\/wp\/v2\/pages\/679332614\/revisions\/679332816"}],"wp:attachment":[{"href":"https:\/\/www.eisgroup.com\/fr\/wp-json\/wp\/v2\/media?parent=679332614"}],"wp:term":[{"taxonomy":"difl_page_category","embeddable":true,"href":"https:\/\/www.eisgroup.com\/fr\/wp-json\/wp\/v2\/difl_page_category?post=679332614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}